{"id":57995,"date":"2024-07-04T18:35:30","date_gmt":"2024-07-04T21:35:30","guid":{"rendered":"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/?p=57995"},"modified":"2024-07-04T18:35:30","modified_gmt":"2024-07-04T21:35:30","slug":"eric-gordon","status":"publish","type":"post","link":"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/basquete\/nba\/eric-gordon\/","title":{"rendered":"Eric Gordon: os n\u00fameros do jogador na NBA"},"content":{"rendered":"\n<p>Eric Gordon \u00e9 conhecido por sua habilidade como ala-armador. Atualmente, ele joga pelo <a href=\"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/basquete\/nba\/phoenix-suns-na-comunidade-nba-0424\/\" target=\"_blank\" rel=\"noreferrer noopener\">Phoenix Suns<\/a> na NBA, mas sua carreira come\u00e7ou muito antes e o jogador brilhou por outras franquias antes de chegar aos Suns em 2023.<\/p>\n\n\n\n<p>Eric Gordon come\u00e7ou a se destacar ainda no ensino m\u00e9dio e frequentou a North Central High School, em Indian\u00e1polis.\u00a0<\/p>\n\n\n\n<p>Durante seu \u00faltimo ano, o jogador teve uma m\u00e9dia impressionante de 29 pontos, 6.2 rebotes e 3.3 assist\u00eancias por jogo, com uma porcentagem de acerto de 57% nos arremessos de campo e 46.2% nas bolas de tr\u00eas pontos\u200b\u200b.&nbsp;<\/p>\n\n\n\n<p>Este alto n\u00edvel de atua\u00e7\u00e3o resultou no apelido &#8220;Mr. Basketball&#8221; de Indiana em 2007 e a ser um All-American no McDonald&#8217;s.<\/p>\n\n\n\n<p>Depois de uma disputa de recrutamento acirrada, Gordon optou por jogar pela Universidade de Indiana, onde rapidamente se tornou uma grande promessa do basquete.&nbsp;<\/p>\n\n\n\n<p>Em sua \u00fanica temporada universit\u00e1ria, ele liderou os Hoosiers com uma m\u00e9dia de 20.9 pontos por jogo, estabelecendo um recorde de calouro na universidade.\u00a0Al\u00e9m disso, ele tamb\u00e9m foi nomeado para o First Team All-Big Ten e foi finalista para o Pr\u00eamio Wooden\u200b.<\/p>\n\n\n\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_73 counter-hierarchy ez-toc-counter ez-toc-light-blue ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Veja no conte\u00fado:<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Alternar tabela de conte\u00fado\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"#\" data-href=\"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/basquete\/nba\/eric-gordon\/#Inicio_de_Eric_Gordon_na_NBA\" title=\"In\u00edcio de Eric Gordon na NBA\">In\u00edcio de Eric Gordon na NBA<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"#\" data-href=\"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/basquete\/nba\/eric-gordon\/#Passagens_notaveis\" title=\"Passagens not\u00e1veis\">Passagens not\u00e1veis<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"#\" data-href=\"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/basquete\/nba\/eric-gordon\/#Eric_Gordon_pelo_Phoenix_Suns\" title=\"Eric Gordon pelo Phoenix Suns&nbsp;\">Eric Gordon pelo Phoenix Suns&nbsp;<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"#\" data-href=\"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/basquete\/nba\/eric-gordon\/#Estatisticas_de_carreira\" title=\"Estat\u00edsticas de carreira\">Estat\u00edsticas de carreira<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"#\" data-href=\"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/basquete\/nba\/eric-gordon\/#Estatisticas_gerais_de_Eric_Gordon\" title=\"Estat\u00edsticas gerais de Eric Gordon\">Estat\u00edsticas gerais de Eric Gordon<\/a><ul class='ez-toc-list-level-4' ><li class='ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"#\" data-href=\"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/basquete\/nba\/eric-gordon\/#Temporada_2023-24_pelo_Phoenix_Suns\" title=\"Temporada 2023-24 pelo Phoenix Suns:\">Temporada 2023-24 pelo Phoenix Suns:<\/a><\/li><\/ul><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n<h2 class=\"wp-block-heading\" id=\"h-inicio-de-eric-gordon-na-nba\"><span class=\"ez-toc-section\" id=\"Inicio_de_Eric_Gordon_na_NBA\"><\/span>In\u00edcio de Eric Gordon na NBA<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Eric Gordon foi a 7\u00aa escolha geral no Draft da NBA de 2008, selecionado pelo Los Angeles Clippers.&nbsp;<\/p>\n\n\n\n<p>Em sua temporada de estreia, ele teve uma \u00f3tima m\u00e9dia de 16.1 pontos por jogo, sendo nomeado para o NBA All-Rookie Second Team.&nbsp;<\/p>\n\n\n\n<p>Assim sendo, Gordon virou um dos principais pontuadores da liga gra\u00e7as \u00e0 sua habilidade de arremessos de tr\u00eas pontos e \u00e0 sua capacidade de infiltra\u00e7\u00e3o na defesa advers\u00e1ria\u200b.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-passagens-notaveis\"><span class=\"ez-toc-section\" id=\"Passagens_notaveis\"><\/span>Passagens not\u00e1veis<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Apesar de ter vividos grandes momentos pelos Clippers, Gordon trocou a franquia para defender o New Orleans Hornets (agora Pelicans) em 2011 como parte da troca que envolveu Chris Paul.&nbsp;<\/p>\n\n\n\n<p>Em Nova Orleans, apesar de lutar com algumas les\u00f5es, ele continuou a fazer grandes atua\u00e7\u00f5es em quadra, especialmente como um arremessador de tr\u00eas pontos.&nbsp;<\/p>\n\n\n\n<p>Durante a temporada 2016\u201317, jogando pelo Houston Rockets, Eric Gordon foi eleito o Sexto Homem do Ano da NBA, com uma m\u00e9dia de 16.2 pontos por jogo e 37.2% de aproveitamento nas bolas de tr\u00eas.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-eric-gordon-pelo-phoenix-suns-nbsp\"><span class=\"ez-toc-section\" id=\"Eric_Gordon_pelo_Phoenix_Suns\"><\/span>Eric Gordon pelo Phoenix Suns&nbsp;<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Em 2023, Eric Gordon assinou com o Phoenix Suns. Na temporada 2023\u201324, ele jogou 68 jogos, dos quais foi titular em 24.\u00a0<\/p>\n\n\n\n<p>Ele teve uma m\u00e9dia de 11 pontos por jogo, com 44.3% de aproveitamento nos arremessos de campo e 37.8% nas bolas de tr\u00eas pontos.&nbsp;<\/p>\n\n\n\n<p>Gordon tamb\u00e9m contribuiu com uma m\u00e9dia de 2 rebotes e 1.6 assist\u00eancias por jogo.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-estatisticas-de-carreira\"><span class=\"ez-toc-section\" id=\"Estatisticas_de_carreira\"><\/span>Estat\u00edsticas de carreira<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Ao longo de sua carreira, Eric Gordon disputou 886 jogos na temporada regular, com m\u00e9dias de 15.7 pontos, 2.3 rebotes e 2.8 assist\u00eancias por jogo.&nbsp;<\/p>\n\n\n\n<p>Ele tem um aproveitamento de 43% nos arremessos de campo, 37.1% nas bolas de tr\u00eas e 81.1% nos lances livres.\u00a0Al\u00e9m disso, nos <em>playoffs<\/em>, ele manteve uma m\u00e9dia s\u00f3lida de 15.1 pontos por jogo.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-estatisticas-gerais-de-eric-gordon\"><span class=\"ez-toc-section\" id=\"Estatisticas_gerais_de_Eric_Gordon\"><\/span>Estat\u00edsticas gerais de Eric Gordon<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>M\u00e9dia de pontos na carreira<\/strong>: 15.7 pontos por jogo<\/li>\n\n\n\n<li><strong>M\u00e9dia de rebotes na carreira<\/strong>: 2.3 rebotes por jogo<\/li>\n\n\n\n<li><strong>M\u00e9dia de assist\u00eancias na carreira<\/strong>: 2.8 assist\u00eancias por jogo<\/li>\n\n\n\n<li><strong>Aproveitamento de arremessos de campo<\/strong>: 43%<\/li>\n\n\n\n<li><strong>Aproveitamento de arremessos de tr\u00eas pontos<\/strong>: 37.1%<\/li>\n\n\n\n<li><strong>Aproveitamento de lances livres<\/strong>: 81.1%<\/li>\n\n\n\n<li><strong>Jogos na temporada regular<\/strong>: 886 jogos<\/li>\n\n\n\n<li><strong>M\u00e9dia de pontos nos playoffs<\/strong>: 15.1 pontos por jogo<\/li>\n<\/ul>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-temporada-2023-24-pelo-phoenix-suns\"><span class=\"ez-toc-section\" id=\"Temporada_2023-24_pelo_Phoenix_Suns\"><\/span>Temporada 2023-24 pelo Phoenix Suns:<span class=\"ez-toc-section-end\"><\/span><\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Jogos disputados<\/strong>: 68 jogos<\/li>\n\n\n\n<li><strong>Jogos como titular<\/strong>: 24 jogos<\/li>\n\n\n\n<li><strong>M\u00e9dia de pontos<\/strong>: 11 pontos por jogo<\/li>\n\n\n\n<li><strong>Rebotes por jogo<\/strong>: 2 rebotes<\/li>\n\n\n\n<li><strong>Assist\u00eancias por jogo<\/strong>: 1.6 assist\u00eancias<\/li>\n\n\n\n<li><strong>Aproveitamento de arremessos de campo<\/strong>: 44.3%<\/li>\n\n\n\n<li><strong>Aproveitamento de arremessos de tr\u00eas pontos<\/strong>: 37.8%<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Eric Gordon \u00e9 conhecido por sua habilidade como ala-armador. Atualmente, ele joga pelo Phoenix Suns na NBA, mas sua carreira come\u00e7ou muito antes e o jogador brilhou por outras franquias &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"Eric Gordon: os n\u00fameros do jogador na NBA\" class=\"read-more button\" href=\"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/basquete\/nba\/eric-gordon\/#more-57995\" aria-label=\"Read more about Eric Gordon: os n\u00fameros do jogador na NBA\">Leia mais<\/a><\/p>\n","protected":false},"author":54,"featured_media":65723,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[1701],"tags":[],"class_list":["post-57995","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nba","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-33","no-featured-image-padding","resize-featured-image"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v23.9 (Yoast SEO v24.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Eric Gordon na NBA: estat\u00edsticas completas | Sportingbet<\/title>\n<meta name=\"description\" content=\"Confira os n\u00fameros e as estat\u00edsticas de Eric Gordon pelas franquias da NBA por onde ele jogou e muito mais.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/basquete\/nba\/eric-gordon\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Eric Gordon: os n\u00fameros do jogador na NBA\" \/>\n<meta property=\"og:description\" content=\"Confira os n\u00fameros e as estat\u00edsticas de Eric Gordon pelas franquias da NBA por onde ele jogou e muito mais.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/basquete\/nba\/eric-gordon\/\" \/>\n<meta property=\"og:site_name\" content=\"sportingbet Brasil\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/sportingbetbrasiloficial\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-04T21:35:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blogs-entain-media.s3.eu-west-1.amazonaws.com\/sportingbet\/pt-br\/blog\/wp-content\/uploads\/2024\/07\/04183455\/D4YW77-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1706\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Lucas Eloy\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@SportingbetBR\" \/>\n<meta name=\"twitter:site\" content=\"@SportingbetBR\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lucas Eloy\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/basquete\/nba\/eric-gordon\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/basquete\/nba\/eric-gordon\/\"},\"author\":{\"name\":\"Lucas Eloy\",\"@id\":\"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/#\/schema\/person\/00a068767786583d4475d4439aa2ae73\"},\"headline\":\"Eric Gordon: os n\u00fameros do jogador na NBA\",\"datePublished\":\"2024-07-04T21:35:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/basquete\/nba\/eric-gordon\/\"},\"wordCount\":602,\"publisher\":{\"@id\":\"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/basquete\/nba\/eric-gordon\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/blogs-entain-media.s3.eu-west-1.amazonaws.com\/sportingbet\/pt-br\/blog\/wp-content\/uploads\/2024\/07\/04183455\/D4YW77-scaled.jpg\",\"articleSection\":[\"NBA\"],\"inLanguage\":\"pt-BR\",\"copyrightYear\":\"2024\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/basquete\/nba\/eric-gordon\/\",\"url\":\"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/basquete\/nba\/eric-gordon\/\",\"name\":\"Eric Gordon na NBA: estat\u00edsticas completas | Sportingbet\",\"isPartOf\":{\"@id\":\"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/basquete\/nba\/eric-gordon\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/basquete\/nba\/eric-gordon\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/blogs-entain-media.s3.eu-west-1.amazonaws.com\/sportingbet\/pt-br\/blog\/wp-content\/uploads\/2024\/07\/04183455\/D4YW77-scaled.jpg\",\"datePublished\":\"2024-07-04T21:35:30+00:00\",\"description\":\"Confira os n\u00fameros e as estat\u00edsticas de Eric Gordon pelas franquias da NBA por onde ele jogou e muito mais.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/basquete\/nba\/eric-gordon\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/basquete\/nba\/eric-gordon\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/basquete\/nba\/eric-gordon\/#primaryimage\",\"url\":\"https:\/\/blogs-entain-media.s3.eu-west-1.amazonaws.com\/sportingbet\/pt-br\/blog\/wp-content\/uploads\/2024\/07\/04183455\/D4YW77-scaled.jpg\",\"contentUrl\":\"https:\/\/blogs-entain-media.s3.eu-west-1.amazonaws.com\/sportingbet\/pt-br\/blog\/wp-content\/uploads\/2024\/07\/04183455\/D4YW77-scaled.jpg\",\"width\":2560,\"height\":1706,\"caption\":\"D4YW77 March 20, 2013 - New Orleans, Louisiana, United States of America - March 20, 2013: New Orleans Hornets shooting guard Eric Gordon (10) drives with the ball during the NBA basketball game between the New Orleans Hornets and the Boston Celtics at the New Orleans Arena in New Orleans, LA.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/basquete\/nba\/eric-gordon\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Basquete\",\"item\":\"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/basquete\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"NBA\",\"item\":\"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/basquete\/nba\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Eric Gordon: os n\u00fameros do jogador na NBA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/#website\",\"url\":\"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/\",\"name\":\"Blog Oficial da sportingbet Brasil\",\"description\":\"Tudo que voc\u00ea precisa saber para come\u00e7ar a apostar na sportingbet hoje mesmo!\",\"publisher\":{\"@id\":\"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/#organization\",\"name\":\"sportingbet Brasil\",\"url\":\"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/blogs-entain-media.s3.eu-west-1.amazonaws.com\/sportingbet\/pt-br\/blog\/wp-content\/uploads\/2024\/03\/20092310\/sportingbet.svg\",\"contentUrl\":\"https:\/\/blogs-entain-media.s3.eu-west-1.amazonaws.com\/sportingbet\/pt-br\/blog\/wp-content\/uploads\/2024\/03\/20092310\/sportingbet.svg\",\"width\":119,\"height\":20,\"caption\":\"sportingbet Brasil\"},\"image\":{\"@id\":\"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/sportingbetbrasiloficial\",\"https:\/\/x.com\/SportingbetBR\",\"https:\/\/www.instagram.com\/sportingbet.tv\/\",\"https:\/\/www.youtube.com\/@SportingbetBR\",\"https:\/\/www.kwai.com\/@SportingbetBR\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/#\/schema\/person\/00a068767786583d4475d4439aa2ae73\",\"name\":\"Lucas Eloy\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/wp-content\/uploads\/2024\/04\/lucas-96x96.jpeg\",\"contentUrl\":\"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/wp-content\/uploads\/2024\/04\/lucas-96x96.jpeg\",\"caption\":\"Lucas Eloy\"},\"description\":\"Lucas Eloy \u00e9 redator do Blog da Sportingbet. Goleiro e comunicador, escreve sobre esportes e apostas esportivas h\u00e1 mais de 5 anos e j\u00e1 jogou profissionalmente. Hoje, voc\u00ea tamb\u00e9m pode encontr\u00e1-lo pelos campos de futebol da V\u00e1rzea Paulistana e acompanh\u00e1-lo tamb\u00e9m pelo instagram @eloylucas__, onde publica sobre esporte e lances de seus jogos e treinos.\",\"url\":\"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/author\/lucas-eloy\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Eric Gordon na NBA: estat\u00edsticas completas | Sportingbet","description":"Confira os n\u00fameros e as estat\u00edsticas de Eric Gordon pelas franquias da NBA por onde ele jogou e muito mais.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/basquete\/nba\/eric-gordon\/","og_locale":"pt_BR","og_type":"article","og_title":"Eric Gordon: os n\u00fameros do jogador na NBA","og_description":"Confira os n\u00fameros e as estat\u00edsticas de Eric Gordon pelas franquias da NBA por onde ele jogou e muito mais.","og_url":"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/basquete\/nba\/eric-gordon\/","og_site_name":"sportingbet Brasil","article_publisher":"https:\/\/www.facebook.com\/sportingbetbrasiloficial","article_published_time":"2024-07-04T21:35:30+00:00","og_image":[{"width":2560,"height":1706,"url":"https:\/\/blogs-entain-media.s3.eu-west-1.amazonaws.com\/sportingbet\/pt-br\/blog\/wp-content\/uploads\/2024\/07\/04183455\/D4YW77-scaled.jpg","type":"image\/jpeg"}],"author":"Lucas Eloy","twitter_card":"summary_large_image","twitter_creator":"@SportingbetBR","twitter_site":"@SportingbetBR","twitter_misc":{"Escrito por":"Lucas Eloy","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/basquete\/nba\/eric-gordon\/#article","isPartOf":{"@id":"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/basquete\/nba\/eric-gordon\/"},"author":{"name":"Lucas Eloy","@id":"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/#\/schema\/person\/00a068767786583d4475d4439aa2ae73"},"headline":"Eric Gordon: os n\u00fameros do jogador na NBA","datePublished":"2024-07-04T21:35:30+00:00","mainEntityOfPage":{"@id":"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/basquete\/nba\/eric-gordon\/"},"wordCount":602,"publisher":{"@id":"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/#organization"},"image":{"@id":"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/basquete\/nba\/eric-gordon\/#primaryimage"},"thumbnailUrl":"https:\/\/blogs-entain-media.s3.eu-west-1.amazonaws.com\/sportingbet\/pt-br\/blog\/wp-content\/uploads\/2024\/07\/04183455\/D4YW77-scaled.jpg","articleSection":["NBA"],"inLanguage":"pt-BR","copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/basquete\/nba\/eric-gordon\/","url":"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/basquete\/nba\/eric-gordon\/","name":"Eric Gordon na NBA: estat\u00edsticas completas | Sportingbet","isPartOf":{"@id":"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/basquete\/nba\/eric-gordon\/#primaryimage"},"image":{"@id":"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/basquete\/nba\/eric-gordon\/#primaryimage"},"thumbnailUrl":"https:\/\/blogs-entain-media.s3.eu-west-1.amazonaws.com\/sportingbet\/pt-br\/blog\/wp-content\/uploads\/2024\/07\/04183455\/D4YW77-scaled.jpg","datePublished":"2024-07-04T21:35:30+00:00","description":"Confira os n\u00fameros e as estat\u00edsticas de Eric Gordon pelas franquias da NBA por onde ele jogou e muito mais.","breadcrumb":{"@id":"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/basquete\/nba\/eric-gordon\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/basquete\/nba\/eric-gordon\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/basquete\/nba\/eric-gordon\/#primaryimage","url":"https:\/\/blogs-entain-media.s3.eu-west-1.amazonaws.com\/sportingbet\/pt-br\/blog\/wp-content\/uploads\/2024\/07\/04183455\/D4YW77-scaled.jpg","contentUrl":"https:\/\/blogs-entain-media.s3.eu-west-1.amazonaws.com\/sportingbet\/pt-br\/blog\/wp-content\/uploads\/2024\/07\/04183455\/D4YW77-scaled.jpg","width":2560,"height":1706,"caption":"D4YW77 March 20, 2013 - New Orleans, Louisiana, United States of America - March 20, 2013: New Orleans Hornets shooting guard Eric Gordon (10) drives with the ball during the NBA basketball game between the New Orleans Hornets and the Boston Celtics at the New Orleans Arena in New Orleans, LA."},{"@type":"BreadcrumbList","@id":"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/basquete\/nba\/eric-gordon\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/"},{"@type":"ListItem","position":2,"name":"Basquete","item":"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/basquete\/"},{"@type":"ListItem","position":3,"name":"NBA","item":"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/basquete\/nba\/"},{"@type":"ListItem","position":4,"name":"Eric Gordon: os n\u00fameros do jogador na NBA"}]},{"@type":"WebSite","@id":"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/#website","url":"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/","name":"Blog Oficial da sportingbet Brasil","description":"Tudo que voc\u00ea precisa saber para come\u00e7ar a apostar na sportingbet hoje mesmo!","publisher":{"@id":"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/#organization","name":"sportingbet Brasil","url":"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/blogs-entain-media.s3.eu-west-1.amazonaws.com\/sportingbet\/pt-br\/blog\/wp-content\/uploads\/2024\/03\/20092310\/sportingbet.svg","contentUrl":"https:\/\/blogs-entain-media.s3.eu-west-1.amazonaws.com\/sportingbet\/pt-br\/blog\/wp-content\/uploads\/2024\/03\/20092310\/sportingbet.svg","width":119,"height":20,"caption":"sportingbet Brasil"},"image":{"@id":"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/sportingbetbrasiloficial","https:\/\/x.com\/SportingbetBR","https:\/\/www.instagram.com\/sportingbet.tv\/","https:\/\/www.youtube.com\/@SportingbetBR","https:\/\/www.kwai.com\/@SportingbetBR"]},{"@type":"Person","@id":"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/#\/schema\/person\/00a068767786583d4475d4439aa2ae73","name":"Lucas Eloy","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/#\/schema\/person\/image\/","url":"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/wp-content\/uploads\/2024\/04\/lucas-96x96.jpeg","contentUrl":"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/wp-content\/uploads\/2024\/04\/lucas-96x96.jpeg","caption":"Lucas Eloy"},"description":"Lucas Eloy \u00e9 redator do Blog da Sportingbet. Goleiro e comunicador, escreve sobre esportes e apostas esportivas h\u00e1 mais de 5 anos e j\u00e1 jogou profissionalmente. Hoje, voc\u00ea tamb\u00e9m pode encontr\u00e1-lo pelos campos de futebol da V\u00e1rzea Paulistana e acompanh\u00e1-lo tamb\u00e9m pelo instagram @eloylucas__, onde publica sobre esporte e lances de seus jogos e treinos.","url":"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/author\/lucas-eloy\/"}]}},"_links":{"self":[{"href":"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/wp-json\/wp\/v2\/posts\/57995","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/wp-json\/wp\/v2\/users\/54"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/wp-json\/wp\/v2\/comments?post=57995"}],"version-history":[{"count":0,"href":"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/wp-json\/wp\/v2\/posts\/57995\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/wp-json\/wp\/v2\/media\/65723"}],"wp:attachment":[{"href":"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/wp-json\/wp\/v2\/media?parent=57995"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/wp-json\/wp\/v2\/categories?post=57995"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/wp-json\/wp\/v2\/tags?post=57995"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}