{"id":240665,"date":"2026-05-13T10:14:32","date_gmt":"2026-05-13T13:14:32","guid":{"rendered":"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/?p=240665"},"modified":"2026-05-13T10:14:36","modified_gmt":"2026-05-13T13:14:36","slug":"bruno-vicari-palmeiras-pega-o-jacuipense-em-jogo-para-rodar-o-elenco-e-com-big-odd","status":"publish","type":"post","link":"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/futebol\/copa-do-brasil\/bruno-vicari-palmeiras-pega-o-jacuipense-em-jogo-para-rodar-o-elenco-e-com-big-odd\/","title":{"rendered":"Bruno Vicari: Palmeiras pega o Jacuipense em jogo para rodar o elenco e com BIG ODD"},"content":{"rendered":"\n<p>Muito bem, pessoal, vamos l\u00e1. Partida decisiva e importante, mata-mata da Copa do Brasil, o <a href=\"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/futebol\/copa-do-brasil\/jacuipense-x-palmeiras-odds-e-palpites-da-copa-do-brasil-13-05\/\">Palmeiras faz sua partida de volta contra o Jacuipense nesta fase da competi\u00e7\u00e3o<\/a>. Conseguiu uma vantagem muito grande no primeiro jogo, venceu tranquilo por 3 a 0, carrega ent\u00e3o essa vantagem.<\/p>\n\n\n\n<p class=\"has-text-align-center\">\u25b6\ufe0f&nbsp;<strong>AN\u00c1LISE EM V\u00cdDEO<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-video\"><video height=\"1080\" style=\"aspect-ratio: 1920 \/ 1080;\" width=\"1920\" controls src=\"https:\/\/blogs-entain-media.s3.eu-west-1.amazonaws.com\/sportingbet\/pt-br\/blog\/wp-content\/uploads\/2026\/05\/13100748\/Bruno-Vicari-Jacuipense-x-Palmeiras.mov\"><\/video><\/figure>\n\n\n\n<p>Mas a\u00ed alguns pontos que s\u00e3o muito importantes a gente ter no\u00e7\u00e3o para esse jogo. Primeiro, por conta do desgaste e da sequ\u00eancia de jogos daqui para frente, talvez esse seja o \u00faltimo respiro que o Palmeiras vai ter na tabela antes da parada para a Copa do Mundo. Daqui pra frente, eu vou at\u00e9 colocar aqui, s\u00e3o jogos muito importantes, por exemplo, primeiro contra o Cruzeiro, depois Flamengo no Campeonato Brasileiro, al\u00e9m das partidas dessa reta final da fase de grupos da Conmebol Libertadores.<\/p>\n\n\n\n<p>Ent\u00e3o, nessa sequ\u00eancia de jogos, daqui pra frente o Palmeiras vai ter que colocar o p\u00e9 embaixo. Ent\u00e3o aqui \u00e9 o \u00faltimo respiro, por conta at\u00e9 da vantagem que tem, para o Abel Ferreira rodar bastante o elenco.<\/p>\n\n\n\n<p>Vale lembrar que o primeiro jogo foi fisicamente muito pegado, alguns jogadores se desgastaram e se contundiram, como foi o caso do Vitor Roque, ent\u00e3o \u00e9 mais um motivo para o Abel pensar nisso e mexer um pouco na escala\u00e7\u00e3o. O Andreas Pereira, por exemplo, tem um problema nas costas e tamb\u00e9m deve ficar fora. Ent\u00e3o vai ser interessante a gente ver como o Abel vai montar a equipe para esse jogo diante desses desgastes e da vantagem que o Palmeiras tem.<\/p>\n\n\n\n<p>Mesmo assim, \u00e9 um Palmeiras que tem que jogar para convencer a sua torcida, recuperar a confian\u00e7a e mostrar um bom futebol. Por isso, tem <strong>BIG ODD da Sportingbet<\/strong> para essa partida. Subindo de 3.10 para 4.00, com um jogo com muitos gols e vit\u00f3ria do Palmeiras.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"has-text-align-center\"><em><a href=\"https:\/\/www.sportingbet.bet.br\/pt-br\/sports\/eventos\/jacuipense-palmeiras-2:7774920\">BIG ODD Sportingbet: Palmeiras vence e 4 ou mais gols na partida | Odd: 4.00<\/a><\/em><\/p>\n<\/blockquote>\n\n\n\n<p>Acredita nisso? J\u00e1 passa l\u00e1 e faz teu nome.<\/p>\n\n\n<span data-tallysight-widget-type=\"tile\" data-tallysight-widget-id=\"69c9e6d811c8c0892b1c569a\" data-tallysight-widget-config-workspace=\"sporting-bet\"><\/span>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-ficha-tecnica-jacuipense-x-palmeiras\"><br>Ficha t\u00e9cnica: Jacuipense x Palmeiras<\/h2>\n\n\n\n<p><strong>Jogo:<\/strong> Copa do Brasil \u2013 5\u00aa fase<br><strong>Data:<\/strong> Quarta-feira (13\/05\/2026)<br><strong>Hor\u00e1rio:<\/strong> 21h30 (hor\u00e1rio de Bras\u00edlia)<br><strong>Est\u00e1dio:<\/strong> Est\u00e1dio do Caf\u00e9, em Londrina (PR)<\/p>\n\n\n\n<p><em>As odds foram verificadas no momento da produ\u00e7\u00e3o deste conte\u00fado e est\u00e3o sujeitas a mudan\u00e7as. Consulte as odds atualizadas na se\u00e7\u00e3o de&nbsp;apostas esportivas da Sportingbet.<\/em><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Muito bem, pessoal, vamos l\u00e1. Partida decisiva e importante, mata-mata da Copa do Brasil, o Palmeiras faz sua partida de volta contra o Jacuipense nesta fase da competi\u00e7\u00e3o. Conseguiu uma &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"Bruno Vicari: Palmeiras pega o Jacuipense em jogo para rodar o elenco e com BIG ODD\" class=\"read-more button\" href=\"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/futebol\/copa-do-brasil\/bruno-vicari-palmeiras-pega-o-jacuipense-em-jogo-para-rodar-o-elenco-e-com-big-odd\/#more-240665\" aria-label=\"Read more about Bruno Vicari: Palmeiras pega o Jacuipense em jogo para rodar o elenco e com BIG ODD\">Leia mais<\/a><\/p>\n","protected":false},"author":173,"featured_media":240669,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[1755],"tags":[1029],"class_list":["post-240665","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-copa-do-brasil","tag-palmeiras","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-33","no-featured-image-padding","resize-featured-image"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v23.9 (Yoast SEO v24.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Palmeiras pega o Jacuipense em jogo com BIG ODD | Sportingbet<\/title>\n<meta name=\"description\" content=\"Bruno Vicari comenta o jogo Jacuipense x Palmeiras pela Copa do Brasil nesta quarta-feira (13\/05) e destaca BIG ODD da Sportingbet.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/futebol\/copa-do-brasil\/bruno-vicari-palmeiras-pega-o-jacuipense-em-jogo-para-rodar-o-elenco-e-com-big-odd\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Palmeiras pega o Jacuipense em jogo com BIG ODD | Sportingbet\" \/>\n<meta property=\"og:description\" content=\"Bruno Vicari comenta o jogo Jacuipense x Palmeiras pela Copa do Brasil nesta quarta-feira (13\/05) e destaca BIG ODD da Sportingbet.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/futebol\/copa-do-brasil\/bruno-vicari-palmeiras-pega-o-jacuipense-em-jogo-para-rodar-o-elenco-e-com-big-odd\/\" \/>\n<meta property=\"og:site_name\" content=\"sportingbet Brasil\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/sportingbetbrasiloficial\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-13T13:14:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T13:14:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blogs-entain-media.s3.eu-west-1.amazonaws.com\/sportingbet\/pt-br\/blog\/wp-content\/uploads\/2026\/05\/12092735\/Bruno-Vicari-Jacuipense-x-Palmeiras-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1703\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Bruno Vicari\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Palmeiras pega o Jacuipense em jogo com BIG ODD | Sportingbet\" \/>\n<meta name=\"twitter:description\" content=\"Bruno Vicari comenta o jogo Jacuipense x Palmeiras pela Copa do Brasil nesta quarta-feira (13\/05) e destaca BIG ODD da Sportingbet.\" \/>\n<meta name=\"twitter:creator\" content=\"@brunovicari\" \/>\n<meta name=\"twitter:site\" content=\"@SportingbetBR\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Bruno Vicari\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/futebol\/copa-do-brasil\/bruno-vicari-palmeiras-pega-o-jacuipense-em-jogo-para-rodar-o-elenco-e-com-big-odd\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/futebol\/copa-do-brasil\/bruno-vicari-palmeiras-pega-o-jacuipense-em-jogo-para-rodar-o-elenco-e-com-big-odd\/\"},\"author\":{\"name\":\"Bruno Vicari\",\"@id\":\"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/#\/schema\/person\/c0e3e1250707110931a64f010250ac39\"},\"headline\":\"Bruno Vicari: Palmeiras pega o Jacuipense em jogo para rodar o elenco e com BIG ODD\",\"datePublished\":\"2026-05-13T13:14:32+00:00\",\"dateModified\":\"2026-05-13T13:14:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/futebol\/copa-do-brasil\/bruno-vicari-palmeiras-pega-o-jacuipense-em-jogo-para-rodar-o-elenco-e-com-big-odd\/\"},\"wordCount\":426,\"publisher\":{\"@id\":\"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/futebol\/copa-do-brasil\/bruno-vicari-palmeiras-pega-o-jacuipense-em-jogo-para-rodar-o-elenco-e-com-big-odd\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/blogs-entain-media.s3.eu-west-1.amazonaws.com\/sportingbet\/pt-br\/blog\/wp-content\/uploads\/2026\/05\/12092735\/Bruno-Vicari-Jacuipense-x-Palmeiras-scaled.jpg\",\"keywords\":[\"Palmeiras\"],\"articleSection\":[\"Copa do Brasil\"],\"inLanguage\":\"pt-BR\",\"copyrightYear\":\"2026\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/futebol\/copa-do-brasil\/bruno-vicari-palmeiras-pega-o-jacuipense-em-jogo-para-rodar-o-elenco-e-com-big-odd\/\",\"url\":\"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/futebol\/copa-do-brasil\/bruno-vicari-palmeiras-pega-o-jacuipense-em-jogo-para-rodar-o-elenco-e-com-big-odd\/\",\"name\":\"Palmeiras pega o Jacuipense em jogo com BIG ODD | Sportingbet\",\"isPartOf\":{\"@id\":\"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/futebol\/copa-do-brasil\/bruno-vicari-palmeiras-pega-o-jacuipense-em-jogo-para-rodar-o-elenco-e-com-big-odd\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/futebol\/copa-do-brasil\/bruno-vicari-palmeiras-pega-o-jacuipense-em-jogo-para-rodar-o-elenco-e-com-big-odd\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/blogs-entain-media.s3.eu-west-1.amazonaws.com\/sportingbet\/pt-br\/blog\/wp-content\/uploads\/2026\/05\/12092735\/Bruno-Vicari-Jacuipense-x-Palmeiras-scaled.jpg\",\"datePublished\":\"2026-05-13T13:14:32+00:00\",\"dateModified\":\"2026-05-13T13:14:36+00:00\",\"description\":\"Bruno Vicari comenta o jogo Jacuipense x Palmeiras pela Copa do Brasil nesta quarta-feira (13\/05) e destaca BIG ODD da Sportingbet.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/futebol\/copa-do-brasil\/bruno-vicari-palmeiras-pega-o-jacuipense-em-jogo-para-rodar-o-elenco-e-com-big-odd\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/futebol\/copa-do-brasil\/bruno-vicari-palmeiras-pega-o-jacuipense-em-jogo-para-rodar-o-elenco-e-com-big-odd\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/futebol\/copa-do-brasil\/bruno-vicari-palmeiras-pega-o-jacuipense-em-jogo-para-rodar-o-elenco-e-com-big-odd\/#primaryimage\",\"url\":\"https:\/\/blogs-entain-media.s3.eu-west-1.amazonaws.com\/sportingbet\/pt-br\/blog\/wp-content\/uploads\/2026\/05\/12092735\/Bruno-Vicari-Jacuipense-x-Palmeiras-scaled.jpg\",\"contentUrl\":\"https:\/\/blogs-entain-media.s3.eu-west-1.amazonaws.com\/sportingbet\/pt-br\/blog\/wp-content\/uploads\/2026\/05\/12092735\/Bruno-Vicari-Jacuipense-x-Palmeiras-scaled.jpg\",\"width\":2560,\"height\":1703,\"caption\":\"3DTD532 Barueri, Sao Paulo, Brasil. 21st Feb, 2026. Barueri (SP), 21\/02\/2026 - Paulista\/Palmeiras vs Capivariano - Ramon Sosa celebrates his goal in the match between Palmeiras and Capivariano, for the quarterfinals of the Paulista football championship, on the night of Saturday, February 21, 2026, at Arena Barueri, in the city of Barueri-SP. (Credit Image: \u00a9 Ronaldo Barreto\/TheNEWS2 via ZUMA Press Wire) EDITORIAL USAGE ONLY! Not for Commercial USAGE!\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/futebol\/copa-do-brasil\/bruno-vicari-palmeiras-pega-o-jacuipense-em-jogo-para-rodar-o-elenco-e-com-big-odd\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Futebol\",\"item\":\"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/futebol\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Copa do Brasil\",\"item\":\"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/futebol\/copa-do-brasil\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Bruno Vicari: Palmeiras pega o Jacuipense em jogo para rodar o elenco e com BIG ODD\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/#website\",\"url\":\"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/\",\"name\":\"Blog Oficial da sportingbet Brasil\",\"description\":\"Tudo que voc\u00ea precisa saber para come\u00e7ar a apostar na sportingbet hoje mesmo!\",\"publisher\":{\"@id\":\"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/#organization\",\"name\":\"sportingbet Brasil\",\"url\":\"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/blogs-entain-media.s3.eu-west-1.amazonaws.com\/sportingbet\/pt-br\/blog\/wp-content\/uploads\/2024\/03\/20092310\/sportingbet.svg\",\"contentUrl\":\"https:\/\/blogs-entain-media.s3.eu-west-1.amazonaws.com\/sportingbet\/pt-br\/blog\/wp-content\/uploads\/2024\/03\/20092310\/sportingbet.svg\",\"width\":119,\"height\":20,\"caption\":\"sportingbet Brasil\"},\"image\":{\"@id\":\"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/sportingbetbrasiloficial\",\"https:\/\/x.com\/SportingbetBR\",\"https:\/\/www.instagram.com\/sportingbet.tv\/\",\"https:\/\/www.youtube.com\/@SportingbetBR\",\"https:\/\/www.kwai.com\/@SportingbetBR\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/#\/schema\/person\/c0e3e1250707110931a64f010250ac39\",\"name\":\"Bruno Vicari\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/wp-content\/uploads\/2025\/09\/cropped-IMG_8050-scaled-1-96x96.jpg\",\"contentUrl\":\"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/wp-content\/uploads\/2025\/09\/cropped-IMG_8050-scaled-1-96x96.jpg\",\"caption\":\"Bruno Vicari\"},\"description\":\"Jornalista, apresentador da ESPN e embaixador da parceria entre Sportingbet e Palmeiras. Traz ao blog an\u00e1lises sobre os jogos do Palmeiras e um olhar reflexivo sobre a atualidade do maior campe\u00e3o brasileiro.\",\"sameAs\":[\"https:\/\/www.instagram.com\/brunovicari\/\",\"https:\/\/x.com\/brunovicari\"],\"url\":\"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/author\/bruno-vicari\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Palmeiras pega o Jacuipense em jogo com BIG ODD | Sportingbet","description":"Bruno Vicari comenta o jogo Jacuipense x Palmeiras pela Copa do Brasil nesta quarta-feira (13\/05) e destaca BIG ODD da Sportingbet.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/futebol\/copa-do-brasil\/bruno-vicari-palmeiras-pega-o-jacuipense-em-jogo-para-rodar-o-elenco-e-com-big-odd\/","og_locale":"pt_BR","og_type":"article","og_title":"Palmeiras pega o Jacuipense em jogo com BIG ODD | Sportingbet","og_description":"Bruno Vicari comenta o jogo Jacuipense x Palmeiras pela Copa do Brasil nesta quarta-feira (13\/05) e destaca BIG ODD da Sportingbet.","og_url":"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/futebol\/copa-do-brasil\/bruno-vicari-palmeiras-pega-o-jacuipense-em-jogo-para-rodar-o-elenco-e-com-big-odd\/","og_site_name":"sportingbet Brasil","article_publisher":"https:\/\/www.facebook.com\/sportingbetbrasiloficial","article_published_time":"2026-05-13T13:14:32+00:00","article_modified_time":"2026-05-13T13:14:36+00:00","og_image":[{"width":2560,"height":1703,"url":"https:\/\/blogs-entain-media.s3.eu-west-1.amazonaws.com\/sportingbet\/pt-br\/blog\/wp-content\/uploads\/2026\/05\/12092735\/Bruno-Vicari-Jacuipense-x-Palmeiras-scaled.jpg","type":"image\/jpeg"}],"author":"Bruno Vicari","twitter_card":"summary_large_image","twitter_title":"Palmeiras pega o Jacuipense em jogo com BIG ODD | Sportingbet","twitter_description":"Bruno Vicari comenta o jogo Jacuipense x Palmeiras pela Copa do Brasil nesta quarta-feira (13\/05) e destaca BIG ODD da Sportingbet.","twitter_creator":"@brunovicari","twitter_site":"@SportingbetBR","twitter_misc":{"Escrito por":"Bruno Vicari","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/futebol\/copa-do-brasil\/bruno-vicari-palmeiras-pega-o-jacuipense-em-jogo-para-rodar-o-elenco-e-com-big-odd\/#article","isPartOf":{"@id":"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/futebol\/copa-do-brasil\/bruno-vicari-palmeiras-pega-o-jacuipense-em-jogo-para-rodar-o-elenco-e-com-big-odd\/"},"author":{"name":"Bruno Vicari","@id":"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/#\/schema\/person\/c0e3e1250707110931a64f010250ac39"},"headline":"Bruno Vicari: Palmeiras pega o Jacuipense em jogo para rodar o elenco e com BIG ODD","datePublished":"2026-05-13T13:14:32+00:00","dateModified":"2026-05-13T13:14:36+00:00","mainEntityOfPage":{"@id":"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/futebol\/copa-do-brasil\/bruno-vicari-palmeiras-pega-o-jacuipense-em-jogo-para-rodar-o-elenco-e-com-big-odd\/"},"wordCount":426,"publisher":{"@id":"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/#organization"},"image":{"@id":"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/futebol\/copa-do-brasil\/bruno-vicari-palmeiras-pega-o-jacuipense-em-jogo-para-rodar-o-elenco-e-com-big-odd\/#primaryimage"},"thumbnailUrl":"https:\/\/blogs-entain-media.s3.eu-west-1.amazonaws.com\/sportingbet\/pt-br\/blog\/wp-content\/uploads\/2026\/05\/12092735\/Bruno-Vicari-Jacuipense-x-Palmeiras-scaled.jpg","keywords":["Palmeiras"],"articleSection":["Copa do Brasil"],"inLanguage":"pt-BR","copyrightYear":"2026","copyrightHolder":{"@id":"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/futebol\/copa-do-brasil\/bruno-vicari-palmeiras-pega-o-jacuipense-em-jogo-para-rodar-o-elenco-e-com-big-odd\/","url":"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/futebol\/copa-do-brasil\/bruno-vicari-palmeiras-pega-o-jacuipense-em-jogo-para-rodar-o-elenco-e-com-big-odd\/","name":"Palmeiras pega o Jacuipense em jogo com BIG ODD | Sportingbet","isPartOf":{"@id":"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/futebol\/copa-do-brasil\/bruno-vicari-palmeiras-pega-o-jacuipense-em-jogo-para-rodar-o-elenco-e-com-big-odd\/#primaryimage"},"image":{"@id":"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/futebol\/copa-do-brasil\/bruno-vicari-palmeiras-pega-o-jacuipense-em-jogo-para-rodar-o-elenco-e-com-big-odd\/#primaryimage"},"thumbnailUrl":"https:\/\/blogs-entain-media.s3.eu-west-1.amazonaws.com\/sportingbet\/pt-br\/blog\/wp-content\/uploads\/2026\/05\/12092735\/Bruno-Vicari-Jacuipense-x-Palmeiras-scaled.jpg","datePublished":"2026-05-13T13:14:32+00:00","dateModified":"2026-05-13T13:14:36+00:00","description":"Bruno Vicari comenta o jogo Jacuipense x Palmeiras pela Copa do Brasil nesta quarta-feira (13\/05) e destaca BIG ODD da Sportingbet.","breadcrumb":{"@id":"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/futebol\/copa-do-brasil\/bruno-vicari-palmeiras-pega-o-jacuipense-em-jogo-para-rodar-o-elenco-e-com-big-odd\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/futebol\/copa-do-brasil\/bruno-vicari-palmeiras-pega-o-jacuipense-em-jogo-para-rodar-o-elenco-e-com-big-odd\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/futebol\/copa-do-brasil\/bruno-vicari-palmeiras-pega-o-jacuipense-em-jogo-para-rodar-o-elenco-e-com-big-odd\/#primaryimage","url":"https:\/\/blogs-entain-media.s3.eu-west-1.amazonaws.com\/sportingbet\/pt-br\/blog\/wp-content\/uploads\/2026\/05\/12092735\/Bruno-Vicari-Jacuipense-x-Palmeiras-scaled.jpg","contentUrl":"https:\/\/blogs-entain-media.s3.eu-west-1.amazonaws.com\/sportingbet\/pt-br\/blog\/wp-content\/uploads\/2026\/05\/12092735\/Bruno-Vicari-Jacuipense-x-Palmeiras-scaled.jpg","width":2560,"height":1703,"caption":"3DTD532 Barueri, Sao Paulo, Brasil. 21st Feb, 2026. Barueri (SP), 21\/02\/2026 - Paulista\/Palmeiras vs Capivariano - Ramon Sosa celebrates his goal in the match between Palmeiras and Capivariano, for the quarterfinals of the Paulista football championship, on the night of Saturday, February 21, 2026, at Arena Barueri, in the city of Barueri-SP. (Credit Image: \u00a9 Ronaldo Barreto\/TheNEWS2 via ZUMA Press Wire) EDITORIAL USAGE ONLY! Not for Commercial USAGE!"},{"@type":"BreadcrumbList","@id":"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/futebol\/copa-do-brasil\/bruno-vicari-palmeiras-pega-o-jacuipense-em-jogo-para-rodar-o-elenco-e-com-big-odd\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/"},{"@type":"ListItem","position":2,"name":"Futebol","item":"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/futebol\/"},{"@type":"ListItem","position":3,"name":"Copa do Brasil","item":"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/futebol\/copa-do-brasil\/"},{"@type":"ListItem","position":4,"name":"Bruno Vicari: Palmeiras pega o Jacuipense em jogo para rodar o elenco e com BIG ODD"}]},{"@type":"WebSite","@id":"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/#website","url":"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/","name":"Blog Oficial da sportingbet Brasil","description":"Tudo que voc\u00ea precisa saber para come\u00e7ar a apostar na sportingbet hoje mesmo!","publisher":{"@id":"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/#organization","name":"sportingbet Brasil","url":"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/blogs-entain-media.s3.eu-west-1.amazonaws.com\/sportingbet\/pt-br\/blog\/wp-content\/uploads\/2024\/03\/20092310\/sportingbet.svg","contentUrl":"https:\/\/blogs-entain-media.s3.eu-west-1.amazonaws.com\/sportingbet\/pt-br\/blog\/wp-content\/uploads\/2024\/03\/20092310\/sportingbet.svg","width":119,"height":20,"caption":"sportingbet Brasil"},"image":{"@id":"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/sportingbetbrasiloficial","https:\/\/x.com\/SportingbetBR","https:\/\/www.instagram.com\/sportingbet.tv\/","https:\/\/www.youtube.com\/@SportingbetBR","https:\/\/www.kwai.com\/@SportingbetBR"]},{"@type":"Person","@id":"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/#\/schema\/person\/c0e3e1250707110931a64f010250ac39","name":"Bruno Vicari","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/#\/schema\/person\/image\/","url":"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/wp-content\/uploads\/2025\/09\/cropped-IMG_8050-scaled-1-96x96.jpg","contentUrl":"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/wp-content\/uploads\/2025\/09\/cropped-IMG_8050-scaled-1-96x96.jpg","caption":"Bruno Vicari"},"description":"Jornalista, apresentador da ESPN e embaixador da parceria entre Sportingbet e Palmeiras. Traz ao blog an\u00e1lises sobre os jogos do Palmeiras e um olhar reflexivo sobre a atualidade do maior campe\u00e3o brasileiro.","sameAs":["https:\/\/www.instagram.com\/brunovicari\/","https:\/\/x.com\/brunovicari"],"url":"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/author\/bruno-vicari\/"}]}},"_links":{"self":[{"href":"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/wp-json\/wp\/v2\/posts\/240665","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/wp-json\/wp\/v2\/users\/173"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/wp-json\/wp\/v2\/comments?post=240665"}],"version-history":[{"count":13,"href":"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/wp-json\/wp\/v2\/posts\/240665\/revisions"}],"predecessor-version":[{"id":240720,"href":"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/wp-json\/wp\/v2\/posts\/240665\/revisions\/240720"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/wp-json\/wp\/v2\/media\/240669"}],"wp:attachment":[{"href":"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/wp-json\/wp\/v2\/media?parent=240665"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/wp-json\/wp\/v2\/categories?post=240665"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sportingbet.bet.br\/pt-br\/blog\/wp-json\/wp\/v2\/tags?post=240665"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}